{"id":43895,"date":"2026-01-16T22:05:26","date_gmt":"2026-01-16T21:05:26","guid":{"rendered":"https:\/\/sergi-energy.com\/accesorios-de-resiliencia\/"},"modified":"2026-01-23T23:51:07","modified_gmt":"2026-01-23T22:51:07","slug":"accesorios-de-resiliencia","status":"publish","type":"page","link":"https:\/\/sergi-energy.com\/es\/soluciones-e-ingenieria\/accesorios-de-resiliencia\/","title":{"rendered":"Accesorios de Resiliencia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"43895\" class=\"elementor elementor-43895 elementor-42630\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f1eb58d e-flex e-con-boxed e-con e-parent\" data-id=\"f1eb58d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d7bde98 e-con-full e-flex e-con e-child\" data-id=\"d7bde98\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63caa30 elementor-widget elementor-widget-the7-breadcrumb\" data-id=\"63caa30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"the7-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"assistive-text\">You are here:<\/div><ol class=\"breadcrumbs text-small rcrumbs\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><i aria-hidden=\"true\" class=\"sn sn-keyboard_arrow_right\"><\/i><a itemprop=\"item\" href=\"https:\/\/sergi-energy.com\/es\/\" title=\"Home\"><span itemprop=\"name\">Home<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><\/li><li class=\"current\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><i aria-hidden=\"true\" class=\"sn sn-keyboard_arrow_right\"><\/i><span itemprop=\"name\">P\u00e1gina<\/span><meta itemprop=\"position\" content=\"2\" \/><\/li><\/ol>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81dcbe1 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-the7-heading\" data-id=\"81dcbe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"the7-heading-title elementor-size-default\">Accesorios de Resiliencia<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-885db33 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-the7-heading\" data-id=\"885db33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"the7-heading-title elementor-size-default\">Componentes dise\u00f1ados que refuerzan arquitecturas de protecci\u00f3n, limitan la escalada y apoyan la recuperaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18daa39 elementor-widget elementor-widget-text-editor\" data-id=\"18daa39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"530\" data-end=\"668\">siempre como parte de una estrategia de sistema integral.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7950777 e-con-full e-flex e-con e-child\" data-id=\"7950777\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7b3a07d e-flex e-con-boxed e-con e-parent\" data-id=\"7b3a07d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ad71af5 e-flex e-con-boxed e-con e-child\" data-id=\"ad71af5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9a746d elementor-widget elementor-widget-text-editor\" data-id=\"a9a746d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"7\">Proteger infraestructuras cr\u00edticas no depende de un solo dispositivo. Requiere capas de prevenci\u00f3n, mitigaci\u00f3n y control de consecuencias, dise\u00f1adas para trabajar conjuntamente. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d41beb7 elementor-align-justify elementor-widget__width-auto elementor-widget elementor-widget-the7_button_widget\" data-id=\"d41beb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"\/es\/?page_id=43963\" class=\"box-button elementor-button elementor-size-lg\">Entiende c\u00f3mo encajan los accesorios en las arquitecturas de protecci\u00f3n<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3c525d8 e-flex e-con-boxed e-con e-child\" data-id=\"3c525d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09b0926 content-align-left the7-hover-visibility-disabled preserve-img-ratio-cover transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"09b0926\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"1428\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%202000%201428&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 2000px) 100vw, 2000px\" style=\"--ratio: 2000 \/ 1428;\" data-src=\"https:\/\/sergi-energy.com\/wp-content\/uploads\/2026\/01\/mantenimiento-electrico-preventivo-onsite-transformador-potencia-disyuntor-transformador-corriente_484521-332.jpg\" loading=\"eager\" data-srcset=\"https:\/\/sergi-energy.com\/wp-content\/uploads\/2026\/01\/mantenimiento-electrico-preventivo-onsite-transformador-potencia-disyuntor-transformador-corriente_484521-332.jpg 2000w, https:\/\/sergi-energy.com\/wp-content\/uploads\/2026\/01\/mantenimiento-electrico-preventivo-onsite-transformador-potencia-disyuntor-transformador-corriente_484521-332-300x214.jpg 300w, https:\/\/sergi-energy.com\/wp-content\/uploads\/2026\/01\/mantenimiento-electrico-preventivo-onsite-transformador-potencia-disyuntor-transformador-corriente_484521-332-1024x731.jpg 1024w, https:\/\/sergi-energy.com\/wp-content\/uploads\/2026\/01\/mantenimiento-electrico-preventivo-onsite-transformador-potencia-disyuntor-transformador-corriente_484521-332-768x548.jpg 768w, https:\/\/sergi-energy.com\/wp-content\/uploads\/2026\/01\/mantenimiento-electrico-preventivo-onsite-transformador-potencia-disyuntor-transformador-corriente_484521-332-1536x1097.jpg 1536w\" \/><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-9cb516f e-flex e-con-boxed e-con e-parent\" data-id=\"9cb516f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdddd2c elementor-widget elementor-widget-heading\" data-id=\"fdddd2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00e1s all\u00e1 de los sistemas de protecci\u00f3n central<\/h2>\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-14009ff e-con-full e-flex e-con e-child\" data-id=\"14009ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c394f23 e-con-full e-flex e-con e-child\" data-id=\"c394f23\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e95ac4 elementor-widget elementor-widget-text-editor\" data-id=\"0e95ac4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1049\" data-end=\"1119\">Sistemas centrales como la <b data-path-to-node=\"11\" data-index-in-node=\"21\">despresurizaci\u00f3n r\u00e1pida<\/b> y <b data-path-to-node=\"11\" data-index-in-node=\"47\">las defensas mec\u00e1nicas de \u00faltima l\u00ednea<\/b> abordan los modos de fallo m\u00e1s cr\u00edticos.<\/p><p data-start=\"1049\" data-end=\"1119\">Sin embargo, <b data-path-to-node=\"11\" data-index-in-node=\"127\">los riesgos espec\u00edficos del lugar<\/b>, las restricciones medioambientales y los requisitos operativos suelen requerir medidas adicionales:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aaff5e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2aaff5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check1\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Limitar la escalada de fuego<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check1\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reducir el impacto ambiental<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check1\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mejorar el tiempo de respuesta<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check1\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Apoyar una recuperaci\u00f3n m\u00e1s r\u00e1pida<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-70849cd e-con-full e-flex e-con e-child\" data-id=\"70849cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7229492 elementor-blockquote--skin-boxed elementor-widget elementor-widget-blockquote\" data-id=\"7229492\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tLos accesorios no evitan eventos catastr\u00f3ficos. Protegen estos eventos de volverse incontrolables. \t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">Key principle<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a5496b5 e-flex e-con-boxed e-con e-parent\" data-id=\"a5496b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39bbb00 elementor-widget elementor-widget-heading\" data-id=\"39bbb00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Persiana Conservator<\/h2>\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d60cc47 e-con-full e-flex e-con e-child\" data-id=\"d60cc47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2d019d1 e-con-full e-flex e-con e-child\" data-id=\"2d019d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2115e52 elementor-widget elementor-widget-heading\" data-id=\"2115e52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contenci\u00f3n y Prevenci\u00f3n de Escalada de Aceite Mec\u00e1nico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6462e61 elementor-widget elementor-widget-text-editor\" data-id=\"6462e61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1049\" data-end=\"1119\">V\u00e1lvula de no retorno puramente mec\u00e1nica que a\u00edsla el conservador, evitando alimentaciones descontroladas de aceite que enciendan el transformador.<\/p><p data-start=\"1049\" data-end=\"1119\"><strong>Qu\u00e9 hace:<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cc7726 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8cc7726\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-arrow_right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A\u00edsla mec\u00e1nicamente al conservador<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-arrow_right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Evita que el aceite adicional alimente el fuego<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-arrow_right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Limita la liberaci\u00f3n de aceite en caso de rotura del dep\u00f3sito<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40478f7 elementor-widget elementor-widget-text-editor\" data-id=\"40478f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"17,2,0\"><b data-path-to-node=\"17,2,0\" data-index-in-node=\"0\">Aplicaciones t\u00edpicas<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b159049 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b159049\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-arrow_right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No previene fallos internos en el transformador<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-arrow_right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No sustituye los sistemas de prevenci\u00f3n de explosiones<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-arrow_right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No sustituye a los sistemas de prevenci\u00f3n de erepitaci\u00f3n (sic)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-arrow_right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No sustituye la prevenci\u00f3n de explosiones<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72348a9 elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-the7_button_widget\" data-id=\"72348a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"\/es\/?page_id=43877\" class=\"box-button elementor-button elementor-size-lg\">Aprende m\u00e1s<i aria-hidden=\"true\" class=\"elementor-button-icon sn sn-arrow-down-right\"><\/i><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7312395 e-con-full e-flex e-con e-child\" data-id=\"7312395\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2027ddd content-align-left the7-hover-visibility-disabled preserve-img-ratio-cover transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"2027ddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1000\" height=\"651\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201000%20651&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1000px) 100vw, 1000px\" style=\"--ratio: 1000 \/ 651;\" data-src=\"https:\/\/sergi-energy.com\/wp-content\/uploads\/2025\/12\/CS.jpg\" loading=\"eager\" data-srcset=\"https:\/\/sergi-energy.com\/wp-content\/uploads\/2025\/12\/CS.jpg 1000w, https:\/\/sergi-energy.com\/wp-content\/uploads\/2025\/12\/CS-300x195.jpg 300w, https:\/\/sergi-energy.com\/wp-content\/uploads\/2025\/12\/CS-768x500.jpg 768w\" \/><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-cd9babb e-flex e-con-boxed e-con e-parent\" data-id=\"cd9babb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a92e199 elementor-widget elementor-widget-heading\" data-id=\"a92e199\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">C\u00f3mo encajan los accesorios de resiliencia en la arquitectura de SERGI<\/h2>\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-866b074 e-con-full e-flex e-con e-child\" data-id=\"866b074\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-722bd51 e-con-full e-grid e-con e-child\" data-id=\"722bd51\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-109c733 e-con-full e-flex e-con e-child\" data-id=\"109c733\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e372e68 elementor-widget elementor-widget-heading\" data-id=\"e372e68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Los accesorios suelen recomendarse cuando:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c2b18f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8c2b18f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">El impacto ambiental debe estar estrictamente controlado<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">El riesgo de escalada de incendio va m\u00e1s all\u00e1 del propio transformador<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Se prioriza la continuidad operativa y la recuperaci\u00f3n r\u00e1pida<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-599119f e-con-full e-flex e-con e-child\" data-id=\"599119f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb5ec16 elementor-widget elementor-widget-heading\" data-id=\"cb5ec16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aplicaciones t\u00edpicas:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c03a44 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5c03a44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Grandes transformadores de potencia rellenos de aceite<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entornos urbanos densos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-33e26d5 e-con-full e-flex e-con e-child\" data-id=\"33e26d5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f60972 elementor-widget elementor-widget-heading\" data-id=\"0f60972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cu\u00e1ndo se recomiendan los accesorios:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b53cdbd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b53cdbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No previene explosiones<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sn sn-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No sustituye a los sistemas de protecci\u00f3n mec\u00e1nica<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>You are here: Home P\u00e1gina Componentes dise\u00f1ados que refuerzan arquitecturas de protecci\u00f3n, limitan la escalada y apoyan la recuperaci\u00f3n siempre como parte de una estrategia de sistema integral. Proteger infraestructuras cr\u00edticas no depende de un solo dispositivo. Requiere capas de prevenci\u00f3n, mitigaci\u00f3n y control de consecuencias, dise\u00f1adas para trabajar conjuntamente. Entiende c\u00f3mo encajan los accesorios&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":44644,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-43895","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sergi-energy.com\/es\/wp-json\/wp\/v2\/pages\/43895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergi-energy.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sergi-energy.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sergi-energy.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergi-energy.com\/es\/wp-json\/wp\/v2\/comments?post=43895"}],"version-history":[{"count":5,"href":"https:\/\/sergi-energy.com\/es\/wp-json\/wp\/v2\/pages\/43895\/revisions"}],"predecessor-version":[{"id":45689,"href":"https:\/\/sergi-energy.com\/es\/wp-json\/wp\/v2\/pages\/43895\/revisions\/45689"}],"up":[{"embeddable":true,"href":"https:\/\/sergi-energy.com\/es\/wp-json\/wp\/v2\/pages\/44644"}],"wp:attachment":[{"href":"https:\/\/sergi-energy.com\/es\/wp-json\/wp\/v2\/media?parent=43895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}